{"id":2347,"date":"2026-08-21T15:01:35","date_gmt":"2026-08-21T13:01:35","guid":{"rendered":"https:\/\/mirkorusrough.com\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/"},"modified":"2026-08-21T15:01:35","modified_gmt":"2026-08-21T13:01:35","slug":"ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen","status":"publish","type":"product","link":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/","title":{"rendered":"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn"},"content":{"rendered":"<p class=\"isSelectedEnd\">Dieser nat\u00fcrliche Peridot zeichnet sich durch eine frische mintgr\u00fcne Farbe und einen ungew\u00f6hnlichen eif\u00f6rmigen Schliff aus, der dem Stein einen unverwechselbaren Charakter verleiht.<\/p>\n<p class=\"isSelectedEnd\">Die Facettierung erzeugt ein lebendiges Spiel aus Reflexionen, bei dem helle Lichtblitze mit tieferen Gr\u00fcnt\u00f6nen kontrastieren. Seine weich gerundete Form macht ihn zu einer interessanten Alternative zu klassischen ovalen und runden Schliffen.<\/p>\n<p class=\"isSelectedEnd\">Der Stein besitzt eine markante nat\u00fcrliche Inklusion sowie mehrere kleinere Einschl\u00fcsse, die auf den Fotos deutlich zu erkennen sind. Anstatt diese zu verbergen, werden diese nat\u00fcrlichen Merkmale bewusst als Teil des individuellen Charakters des Edelsteins gezeigt.<\/p>\n<p>Mit 1,88 ct und 8,5 \u00d7 7,0 mm eignet sich der Peridot hervorragend als zentraler Stein f\u00fcr einen individuell angefertigten Ring oder Anh\u00e4nger.<\/p>\n<p><strong>Spezifikationen<\/strong><\/p>\n<ul>\n<li data-section-id=\"1kohuvl\" data-start=\"1655\" data-end=\"1688\"><strong data-start=\"1657\" data-end=\"1676\">Geschliffen von<\/strong>: Mirko Dokic<\/li>\n<li data-section-id=\"1d0awzn\" data-start=\"1689\" data-end=\"1718\"><strong data-start=\"1691\" data-end=\"1699\">Cut<\/strong>: Egg Cut<\/li>\n<li data-section-id=\"1a5jw5g\" data-start=\"1719\" data-end=\"1756\"><strong data-start=\"1721\" data-end=\"1736\">Stone type:<\/strong> Natural Peridot<\/li>\n<li data-section-id=\"6nm38m\" data-start=\"1757\" data-end=\"1779\"><strong data-start=\"1759\" data-end=\"1770\">Weight<\/strong>: 1.88 ct<\/li>\n<li data-section-id=\"11obbkf\" data-start=\"1780\" data-end=\"1817\"><strong data-start=\"1782\" data-end=\"1797\">Dimensions<\/strong>: 8.5 \u00d7 7.0 \u00d7 5.0 mm<\/li>\n<li data-section-id=\"ehsmmu\" data-start=\"1818\" data-end=\"1842\"><strong data-start=\"1820\" data-end=\"1832\">Clarity<\/strong>: One big inclusion and some smaller.<\/li>\n<li data-section-id=\"1hyqw6k\" data-start=\"1843\" data-end=\"1864\"><strong data-start=\"1845\" data-end=\"1855\">Color<\/strong>: Mint Green<\/li>\n<li data-section-id=\"1ci81fg\" data-start=\"1865\" data-end=\"1896\"><strong data-start=\"1867\" data-end=\"1884\">Transparenz:<\/strong> Transparent<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ein nat\u00fcrlicher Peridot mit 1,88 ct in einem markanten Egg Cut, der sich durch seine frische mintgr\u00fcne Farbe und sein lebendiges Reflexionsspiel auszeichnet. Nat\u00fcrliche Inklusionen verleihen dem Stein seinen individuellen Charakter, w\u00e4hrend er gleichzeitig eine gute Transparenz bewahrt.<\/p>\n","protected":false},"featured_media":2341,"template":"","meta":[],"product_brand":[],"product_cat":[327],"product_tag":[],"class_list":["post-2347","product","type-product","status-publish","has-post-thumbnail","product_cat-peridot","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn - mirkorusrough.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn - mirkorusrough.com\" \/>\n<meta property=\"og:description\" content=\"Ein nat\u00fcrlicher Peridot mit 1,88 ct in einem markanten Egg Cut, der sich durch seine frische mintgr\u00fcne Farbe und sein lebendiges Reflexionsspiel auszeichnet. Nat\u00fcrliche Inklusionen verleihen dem Stein seinen individuellen Charakter, w\u00e4hrend er gleichzeitig eine gute Transparenz bewahrt.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/\" \/>\n<meta property=\"og:site_name\" content=\"mirkorusrough.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/08\/IMG_0006_2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1077\" \/>\n\t<meta property=\"og:image:height\" content=\"1077\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/\",\"url\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/\",\"name\":\"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn - mirkorusrough.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/mirkorusrough.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/IMG_0006_2.jpeg\",\"datePublished\":\"2026-08-21T13:01:35+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/mirkorusrough.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/IMG_0006_2.jpeg\",\"contentUrl\":\"http:\\\/\\\/mirkorusrough.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/IMG_0006_2.jpeg\",\"width\":1077,\"height\":1077,\"caption\":\"Facettierter Peridot im Eierschliff\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/mirkorusrough.com\\\/de\\\/produkt\\\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/\",\"name\":\"Mirkorus Rough\",\"description\":\"Collector Gems &amp; Faceting Rough\",\"publisher\":{\"@id\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/#organization\",\"name\":\"Lapidarius Mirkorus\",\"url\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/mirkorusrough.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/MirkorusRough.png\",\"contentUrl\":\"http:\\\/\\\/mirkorusrough.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/MirkorusRough.png\",\"width\":607,\"height\":434,\"caption\":\"Lapidarius Mirkorus\"},\"image\":{\"@id\":\"https:\\\/\\\/mirkorusrough.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn - mirkorusrough.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/","og_locale":"de_DE","og_type":"article","og_title":"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn - mirkorusrough.com","og_description":"Ein nat\u00fcrlicher Peridot mit 1,88 ct in einem markanten Egg Cut, der sich durch seine frische mintgr\u00fcne Farbe und sein lebendiges Reflexionsspiel auszeichnet. Nat\u00fcrliche Inklusionen verleihen dem Stein seinen individuellen Charakter, w\u00e4hrend er gleichzeitig eine gute Transparenz bewahrt.","og_url":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/","og_site_name":"mirkorusrough.com","og_image":[{"width":1077,"height":1077,"url":"https:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/08\/IMG_0006_2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/","url":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/","name":"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn - mirkorusrough.com","isPartOf":{"@id":"https:\/\/mirkorusrough.com\/de\/#website"},"primaryImageOfPage":{"@id":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/#primaryimage"},"image":{"@id":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/#primaryimage"},"thumbnailUrl":"http:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/08\/IMG_0006_2.jpeg","datePublished":"2026-08-21T13:01:35+00:00","breadcrumb":{"@id":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/#primaryimage","url":"http:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/08\/IMG_0006_2.jpeg","contentUrl":"http:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/08\/IMG_0006_2.jpeg","width":1077,"height":1077,"caption":"Facettierter Peridot im Eierschliff"},{"@type":"BreadcrumbList","@id":"http:\/\/mirkorusrough.com\/de\/produkt\/ei-schliff-%c2%b7-peridot-%c2%b7-facettierter-stein-%c2%b7-188-ct-%c2%b7-minzgruen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/mirkorusrough.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mirkorusrough.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Ei-Schliff \u00b7 Peridot \u00b7 Facettierter Stein \u00b7 1,88 ct \u00b7 Minzgr\u00fcn"}]},{"@type":"WebSite","@id":"https:\/\/mirkorusrough.com\/de\/#website","url":"https:\/\/mirkorusrough.com\/de\/","name":"Mirkorus Rough","description":"Collector Gems &amp; Faceting Rough","publisher":{"@id":"https:\/\/mirkorusrough.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirkorusrough.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mirkorusrough.com\/de\/#organization","name":"Lapidarius Mirkorus","url":"https:\/\/mirkorusrough.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mirkorusrough.com\/de\/#\/schema\/logo\/image\/","url":"http:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/02\/MirkorusRough.png","contentUrl":"http:\/\/mirkorusrough.com\/wp-content\/uploads\/2026\/02\/MirkorusRough.png","width":607,"height":434,"caption":"Lapidarius Mirkorus"},"image":{"@id":"https:\/\/mirkorusrough.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/product\/2347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/media\/2341"}],"wp:attachment":[{"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/media?parent=2347"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/product_brand?post=2347"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/product_cat?post=2347"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/mirkorusrough.com\/de\/wp-json\/wp\/v2\/product_tag?post=2347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}